{"id":15969,"date":"2026-02-10T09:00:00","date_gmt":"2026-02-10T08:00:00","guid":{"rendered":"https:\/\/www.voluntariness.org\/?p=15969"},"modified":"2026-04-17T09:57:55","modified_gmt":"2026-04-17T07:57:55","slug":"jugendfreiwilligendienst-als-gewinn","status":"publish","type":"post","link":"https:\/\/www.voluntariness.org\/de\/jugendfreiwilligendienst-als-gewinn\/","title":{"rendered":"Jugendfreiwilligen-Dienst als Gewinn?"},"content":{"rendered":"\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\"><div class=\"wp-block-image is-style-default\">\n<figure class=\"alignleft size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/www.voluntariness.org\/wp-content\/uploads\/sites\/2\/2026\/01\/jung-frei-und-willig-1-teaser-web.jpg\" alt=\"\" class=\"wp-image-16166\" style=\"aspect-ratio:3\/2;object-fit:contain;width:807px;height:auto\" \/><figcaption class=\"wp-element-caption\">Freiwillige, die in Projekten aus Kultur und Bildung arbeiten m\u00f6chten, werden von Teamer:innen w\u00e4hrend ihres Dienstes geschult und begleitet. \u00a9 privat, bei einem Seminar der <a href=\"https:\/\/www.lkjthueringen.de\/projekte\/freiwilligendienste\">Landesvereinigung Kulturelle Jugendbildung Th\u00fcringen e.V.<\/a><\/figcaption><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-medium is-resized\"><img decoding=\"async\" src=\"https:\/\/www.voluntariness.org\/wp-content\/uploads\/sites\/2\/2026\/01\/haehnlein_ronja_web-250x250.jpg\" alt=\"\" class=\"wp-image-16178\" style=\"width:250px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-content-primary-color has-text-color\">Von <a href=\"https:\/\/www.voluntariness.org\/de\/project\/ronja-haehnlein\/\">Ronja H\u00e4hnlein<\/a><\/p>\n\n\n\n<p>Ronja H\u00e4hnlein studiert Geschichte im Master &#8220;Geschichte transkulturell&#8221; an der Universit\u00e4t Erfurt.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"has-content-bg-alt-background-color has-background\">Dieser Beitrag ist der erste und \u00fcberarbeitete Teil eines Artikels, der Ende 2024 in Heft 99\/Winter 2025 der <a href=\"https:\/\/hastuzeit.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Halleschen Studierendenschaftszeitschrift<\/a> und im <a href=\"https:\/\/hastuzeit.de\/jung-frei-und-willig\/\" target=\"_blank\" rel=\"noreferrer noopener\">M\u00e4rz 2025<\/a> digital erschienen ist. Die Redakteurin Ronja H\u00e4hnlein teilte dort bereits ihre Einsch\u00e4tzung zum gesellschaftlichen und politischen Stellenwert des Jugendfreiwilligendienstes in Deutschland. Als ehemalige Absolventin eines Freiwilligen Sozialen Jahres und im Nebenberuf Teamerin von Freiwilligen bei Bildungsseminaren in Th\u00fcringen kommentiert Ronja damit ein sehr aktuelles Thema aus der ersten Reihe. Ihre Perspektiven, Argumente und pers\u00f6nlichen Erfahrungswerte ordnet sie auch in den Kontext der Debatte um eine Wiedereinf\u00fchrung der Wehrpflicht und damit verbunden in eine Debatte \u00fcber einen verpflichtenden Sozialdienst f\u00fcr junge Menschen ein. In einem Beitrag f\u00fcr unseren Blog vom Juli 2025 fasste bereits <a href=\"https:\/\/www.voluntariness.org\/de\/project\/silke-van-dyk\/\">Silke van Dyk<\/a> von der FSU Jena ihre Sicht als politische Soziologin auf <a href=\"https:\/\/www.voluntariness.org\/de\/organisierter-gemeinsinn-in-krisenzeiten\/\">Pro- und Contra-Argumente zum sozialen Pflichtjahr<\/a> zusammen und die Bundeswehrexpertin <a href=\"https:\/\/www.voluntariness.org\/de\/project\/nina-leonhard\/\">Nina Leonhard<\/a> kommentierte im Oktober 2025 den <a href=\"https:\/\/www.voluntariness.org\/de\/wehrdienst\/\">Streitpunkt Freiwilligkeit bei der Diskussion um die m\u00f6gliche Wiedereinf\u00fchrung des Wehrdienstes<\/a>. Der Post von Ronja H\u00e4hnlein l\u00e4dt nun bewusst dazu ein, den Blick aus der allt\u00e4glichen Praxis heraus auf die vielschichtige Diskussion zu richten. In einem zweiten Teil ihres Textes, der im April 2026 unter dem Titel \u201eMit Freiwilligen auf Augenh\u00f6he: \u00dcber den pers\u00f6nlichen Wert des Jugendfreiwilligendienstes\u201c erscheinen wird, wird sie au\u00dferdem beschreiben, was es f\u00fcr potenzielle Freiwillige bedeuten kann, einen solchen Dienst zu leisten. Wir bedanken uns bei der Redaktion der <a href=\"https:\/\/hastuzeit.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Halleschen Studierendenschaftszeitschrift<\/a> f\u00fcr die Erlaubnis zum Re-Posting der Beitr\u00e4ge!<\/p>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left\" id=\"perspectives-on-voluntariness-and-the-covid-crisis\">Jugendfreiwilligendienst als Gewinn? Eine Kosten-Nutzen-Rechnung mit Erfahrungswerten<\/h2>\n\n\n\n<p>Zuallererst will ich mich outen: Ich bin gro\u00dfer Fan vom Jugendfreiwilligendienst! Die Idee, dass junge Menschen ein Jahr lang in sozialen, \u00f6kologischen oder kulturellen Einrichtungen mitarbeiten und dabei die einen von den anderen lernen und umgekehrt \u2013 wie gro\u00dfartig ist das bitte? Ich will auch behaupten, etwas Ahnung zu haben. Neben der Erfahrung eines eigenen FSJs nach dem Abitur in Jugendclub, Bibliothek und Tourist-Information meines Heimatortes begleite ich, als Nebenjob zum Studium, nun im sechsten Jahr Freiwillige aus dem Th\u00fcringer Kultur- und Politikbereich auf ihren Bildungsseminaren. Dabei habe ich Einblicke in die Perspektiven von Tr\u00e4gern, Einsatzstellen und zahlreichen Freiwilligen bekommen und das hat mich zu meiner \u00dcberzeugung gebracht: Ja, Jugendfreiwilligendienst ist der absolute Kn\u00fcller! Meinem Eindruck nach teilen diese Ansicht jedoch nicht viele. Gesellschaftliche Debatten um das Thema sind beladen mit vielen Widerspr\u00fcchen und Ignoranz, bei denen vor allem eine Instanz immer wieder verliert: die Gesellschaft selbst.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Zahlen bitte!<\/h3>\n\n\n\n<p>2023 wurde eine Petition eingereicht: Innerhalb von vier Wochen konnten \u00fcber 100 000 Unterschriften gesammelt werden, um gegen die f\u00fcr 2024 geplanten Bundeshaushaltsk\u00fcrzungen im Bereich der Freiwilligendienste zu protestieren. Es gelang tats\u00e4chlich, <a href=\"https:\/\/www.diakonie.de\/informieren\/infothek\/2023\/september\/petition-freiwilligendienst-staerken-im-bundestag-freiwilligendienste-massiv-von-kuerzungen-bedroht\">die geplanten K\u00fcrzungen von 78 Millionen Euro wurden ausgesetzt<\/a>. Doch der Erfolg w\u00e4hrte nur kurz. Der Kabinettsentwurf f\u00fcr den Bundeshaushalt 2025, der im darauffolgenden Juli vorgelegt wurde, sah nun eine finanzielle Einsparung von etwa 40 Millionen Euro vor \u2013 das w\u00e4ren K\u00fcrzungen um 12 Prozent gewesen. Allein das vorzeitige Ende der \u201eAmpel-Regierung\u201c hatte dies verhindert. Die aktuelle Bundesregierung indes beschloss k\u00fcrzlich f\u00fcr 2026 eine <a href=\"https:\/\/www.bundestag.de\/presse\/hib\/kurzmeldungen-1127194\">finanzielle Aufstockung von FSJ und Bundesfreiwilligendienst<\/a>. Ein Grund zum Feiern also? Nun ja, einerseits haben die letzten Jahre gezeigt, auf welch wackeligen Beinen die Bundesfinanzierung f\u00fcr die Freiwilligendienste steht, andererseits sind auch die anderen ben\u00f6tigten Geldt\u00f6pfe steten Schwankungen unterlegen.<\/p>\n\n\n\n<p>Insgesamt ist die Finanzierung der Freiwilligendienste eher un\u00fcbersichtlich. Etwas Geld kommt vom Bund, der F\u00f6deralismus gl\u00e4nzt in seinen 16 Facetten, von manchen Bundesl\u00e4ndern werden EU-Gelder angezapft. Gleiches gilt auch bei rechtlichen Fragen wie etwa der Unterscheidung in Freiwilliges Soziales Jahr (FSJ), Freiwilliges \u00d6kologisches Jahr (F\u00d6J) und Bundesfreiwilligendienst (BFD). Zus\u00e4tzlich ist jeder Freiwilligenjahrgang von zwei Finanzhaushalten abh\u00e4ngig, denn in der Regel beginnt der Dienst im September des einen und endet im August des n\u00e4chsten Jahres. All das macht den Jugendfreiwilligendienst nur bedingt planbar und diese Unsicherheit schwebt stetig \u00fcber dem Format. Gleichzeitig und trotz dessen zeigt aber allein die eben erw\u00e4hnte Petition: Der Jugendfreiwilligendienst hat nicht nur mich als Fan.<\/p>\n\n\n\n<p>Doch der Aspekt der Freiwilligkeit scheint nicht allen zu schmecken: Noch als Kanzlerkandidat verk\u00fcndete Friedrich Merz im Rahmen seines Wahlkampfes, er wolle als Regierungschef ein <a href=\"https:\/\/www.cdu.de\/aktuelles\/aussen-und-sicherheitspolitik\/neue-dienstpflicht-soll-wehrdienst-ergaenzen\/\">&#8220;verpflichtendes Gesellschaftsjahr&#8221;<\/a> einf\u00fchren; dieses Mal f\u00fcr M\u00e4nner und Frauen. Im Rahmen dessen soll der Grundwehrdienst und alternativ eine Art Zivildienst obligatorisch werden. Und nicht nur in Kreisen der CDU findet die Idee der Verpflichtung Anklang. Der SPD-Fraktionsvize des Bundestages Dirk Wiese forderte im Sommer 2023 einen sozialen Pflichtdienst f\u00fcr junge Menschen von mindestens drei Monaten: <a href=\"https:\/\/www.spiegel.de\/politik\/spd-plant-anlauf-fuer-sozialen-pflichtdienst-in-deutschland-a-4d663535-95a7-4e12-aa14-e35efa4ac152\">&#8220;Wir brauchen wieder mehr Respekt im Umgang und ein st\u00e4rkeres Miteinander im Land.&#8221;<\/a> Auch <a href=\"https:\/\/www.sueddeutsche.de\/leben\/sozialministerin-toure-offen-fuer-verpflichtendes-gesellschaftsjahr-dpa.urn-newsml-dpa-com-20090101-240508-99-961283\">Aminata Tour\u00e9 (Die Gr\u00fcnen), Sozialministerin Schleswig-Holsteins, sprach sich 2024 f\u00fcr eine Pflicht aus<\/a>, nachdem sie sich <a href=\"https:\/\/www.schleswig-holstein.de\/DE\/landesregierung\/ministerien-behoerden\/VIII\/Presse\/PI\/2022\/220901_VIII_Toure_zu_Freiwilligendienst_Pflicht\">zwei Jahre zuvor noch dagegen positioniert hatte<\/a>.<\/p>\n\n\n\n<div class=\"wp-block-columns has-content-bg-alt-background-color has-background is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group has-medium-font-size\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h3 class=\"wp-block-heading has-medium-font-size\">Wo Jugendfreiwilligendienstleistende unter anderem arbeiten &#8230;<\/h3>\n\n\n\n<div class=\"wp-block-group is-layout-grid wp-container-core-group-is-layout-4d858cb8 wp-block-group-is-layout-grid\">\n<figure class=\"wp-block-image size-us_300_300 wp-container-content-e712e989 wp-duotone-unset-1\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"300\" src=\"https:\/\/www.voluntariness.org\/wp-content\/uploads\/sites\/2\/2026\/01\/Fahrdienst_600-150x300.jpg\" alt=\"\" class=\"wp-image-15988\" srcset=\"https:\/\/www.voluntariness.org\/wp-content\/uploads\/sites\/2\/2026\/01\/Fahrdienst_600-150x300.jpg 150w, https:\/\/www.voluntariness.org\/wp-content\/uploads\/sites\/2\/2026\/01\/Fahrdienst_600-125x250.jpg 125w, https:\/\/www.voluntariness.org\/wp-content\/uploads\/sites\/2\/2026\/01\/Fahrdienst_600.jpg 300w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><figcaption class=\"wp-element-caption\"> &#8230; bei verschiedenen sozialen Fahrdiensten<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-us_300_300\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"300\" src=\"https:\/\/www.voluntariness.org\/wp-content\/uploads\/sites\/2\/2026\/01\/Denkmalschutz_600-150x300.jpg\" alt=\"\" class=\"wp-image-15987\" srcset=\"https:\/\/www.voluntariness.org\/wp-content\/uploads\/sites\/2\/2026\/01\/Denkmalschutz_600-150x300.jpg 150w, https:\/\/www.voluntariness.org\/wp-content\/uploads\/sites\/2\/2026\/01\/Denkmalschutz_600-125x250.jpg 125w, https:\/\/www.voluntariness.org\/wp-content\/uploads\/sites\/2\/2026\/01\/Denkmalschutz_600.jpg 300w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><figcaption class=\"wp-element-caption\"> &#8230; beim Denkmalschutz<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-us_300_300\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"300\" src=\"https:\/\/www.voluntariness.org\/wp-content\/uploads\/sites\/2\/2026\/01\/Sportverein_600-150x300.jpg\" alt=\"\" class=\"wp-image-15992\" srcset=\"https:\/\/www.voluntariness.org\/wp-content\/uploads\/sites\/2\/2026\/01\/Sportverein_600-150x300.jpg 150w, https:\/\/www.voluntariness.org\/wp-content\/uploads\/sites\/2\/2026\/01\/Sportverein_600-125x250.jpg 125w, https:\/\/www.voluntariness.org\/wp-content\/uploads\/sites\/2\/2026\/01\/Sportverein_600.jpg 300w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><figcaption class=\"wp-element-caption\"> &#8230; in Sportvereinen<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-us_300_300\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"300\" src=\"https:\/\/www.voluntariness.org\/wp-content\/uploads\/sites\/2\/2026\/01\/Krankenhauser_600-1-150x300.jpg\" alt=\"\" class=\"wp-image-15990\" srcset=\"https:\/\/www.voluntariness.org\/wp-content\/uploads\/sites\/2\/2026\/01\/Krankenhauser_600-1-150x300.jpg 150w, https:\/\/www.voluntariness.org\/wp-content\/uploads\/sites\/2\/2026\/01\/Krankenhauser_600-1-125x250.jpg 125w, https:\/\/www.voluntariness.org\/wp-content\/uploads\/sites\/2\/2026\/01\/Krankenhauser_600-1.jpg 300w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><figcaption class=\"wp-element-caption\"> &#8230; im Rettungsdienst, in Krankenh\u00e4usern und weiteren medizinischen Einrichtungen<\/figcaption><\/figure>\n<\/div>\n<\/div><\/div>\n\n\n\n<p class=\"has-content-primary-color has-text-color has-link-color wp-elements-1dac133f1aa6c6bb63971fc6e7457d7f\" style=\"font-size:20px\">\u00a9 Alle Illustrationen in diesem Post stammen von Ronja H\u00e4hnlein.<\/p>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Wie stellen Sie sich das vor, Herr Merz?<\/h3>\n\n\n\n<p>Tour\u00e9 selbst meint, sie wisse, dass die Thematik polarisiere, da eine Pflicht einen Eingriff in die individuelle Freiheit darstelle. Damit verweist sie auf das zentrale Argument bei Debatten gegen ein Pflichtjahr. Und ja, das ist grunds\u00e4tzlich ein Gegenstand, den es zu diskutieren gilt, stellt dabei aber auch nur die Spitze des Eisberges an Problemen dar, die sich rund um eine m\u00f6gliche Verpflichtung auftun \u2013 wenn man nur einen genaueren Blick auf die Praxis wirft.<\/p>\n\n\n\n<p>W\u00e4hrend immer wieder dar\u00fcber geredet wird, welche Bereicherung Freiwillige f\u00fcr die Einsatzstellen darstellen, wird allzu gern der damit einhergehende Aufwand vergessen. Jedes Jahr m\u00fcssen Einrichtungen aufs Neue Menschen einarbeiten und betreuen, deren T\u00e4tigkeit nach dem Prinzip der Arbeitsmarktneutralit\u00e4t keine bezahlte Arbeit ersetzen darf. Wie hoch d\u00fcrfte dieser Aufwand nun sein, wenn da ein junger Mensch vor einem steht, der schlichtweg keine Lust hat? Wie viel ist ein Sozialdienst wert, der nicht aus freiwilligem Geben und Lernen, sondern verdonnertem Sich-mitschleifen-Lassen besteht?<\/p>\n\n\n\n<p>Andererseits w\u00fcrden zahllose Dienstleistende in Einrichtungen landen, in denen der Job des Mentorings nicht ordentlich ausgef\u00fcllt werden kann. Wie gesagt, die Anleitung und F\u00f6rderung durch die Einsatzstelle ist auch mit Arbeit verbunden. Das will gelernt sein und muss wiederum auch angeleitet und kontrolliert werden. Die Mitarbeitenden von Freiwilligendiensttr\u00e4gern begleiten die Dienstleistenden unabh\u00e4ngig von ihren Einsatzstellen und agieren oft als Mediator:innen bei Problemen, die zwischen Freiwilligen und Einrichtung auftreten. Sie haben ein liebevolles Auge darauf, ob das Jahr ohne Ausbeutung, Druck oder systematische Langeweile verl\u00e4uft. Diese Aufgabe ist \u00e4u\u00dferst wichtig \u2013 und braucht damit ausreichend Finanzierung und passendes Personal \u2013 w\u00e4hrend gleichzeitig eine gro\u00dfe Zahl neuer Einsatzstellen besonders viel Aufmerksamkeit und damit verbundene Arbeit verlangen w\u00fcrde.<\/p>\n\n\n\n<p>Denken wir das Ganze mit einer Wiedereinf\u00fchrung der Wehrpflicht zusammen, wie es momentan oft im Zusammenhang mit einem Pflichtjahr getan wird, treten weitere Probleme zutage. In der Bundeswehr fehlt es momentan ebenfalls an entsprechenden Strukturen, um eine Wiedereinf\u00fchrung stemmen zu k\u00f6nnen. So braucht es etwa neue Musterungseinrichtungen oder Ministeriumsstellen, in denen Verweigerungsschreiben gepr\u00fcft werden. All diese Strukturen wurden mit dem Aussetzen der Wehrpflicht abgebaut und m\u00fcssen nun wieder neu errichtet werden; <a href=\"https:\/\/www.bmvg.de\/de\/aktuelles\/alles-wichtige-rund-um-den-neuen-wehrdienst-6040510\">bei voller Kapazit\u00e4t sollen 300.000 Musterungen pro Jahrgang gestemmt werden<\/a>. Da diese Zahl allein die wehrpflichtigen M\u00e4nner abdeckt, bedarf es noch zus\u00e4tzlicher Kapazit\u00e4ten f\u00fcr Interessierte anderer Geschlechter. Deren Zahl wiederum d\u00fcrfte bei der Einf\u00fchrung eines allgemeinen Pflichtjahres noch einmal steigen. Und all diese jungen Menschen m\u00fcssen dann ja auch, einmal angekommen in der Bundeswehr, ausgestattet, ausgebildet, versorgt und bezahlt werden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Das liebe Geld<\/h3>\n\n\n\n<p>Grunds\u00e4tzlich w\u00fcrde ich an dieser Stelle einmal die Frage in den Raum werfen, wer das alles bezahlen soll. Bereits eine Wiedereinf\u00fchrung der Wehrpflicht wird teuer, ein verpflichtendes Gesellschaftsjahr w\u00e4re eine weitere massive Investition \u2013 und das, w\u00e4hrend Freiwilligendienste jedes Jahr aufs Neue zittern m\u00fcssen, ob ihr Budget im n\u00e4chsten Jahr erhalten bleibt. Zudem muss eine potenzielle Pflicht allzu gerne als L\u00f6sung f\u00fcr den krassen Personalmangel im sozialen Sektor herhalten. Da werden sch\u00f6ne Bilder gemalt von einer Oma im Pflegeheim, die endlich jemanden hat, mit dem sie Halma spielen kann. Dass Freiwilligendienstleistende offiziell als arbeitsmarktneutral gelten, wird da gerne vergessen. Alternativ verweisen Verfechter:innen der Pflicht bei ihrer Argumentation gerne auf die Tatsache, <a href=\"https:\/\/www.swr.de\/swraktuell\/baden-wuerttemberg\/heilbronn\/bufdi-fsj-freiwilligendienste-bundeshaushalt-kindersolbad-bad-friedrichshall-kuerzungen-100.html\">dass 70 Prozent aller Freiwilligen, die einen sozialen Jugenddienst ableisten, auch sp\u00e4ter eine Ausbildung in der Branche beginnen<\/a>. Aber durch eine Pflicht werden doch nicht automatisch mehr Menschen \u00fcberzeugt und an den prek\u00e4ren Arbeitsbedingungen \u00e4ndert das auch nichts. Es dr\u00e4ngt sich die Frage auf: Wieso nicht direkt das Geld statt in einen Pflichtdienst in deutlich bessere Arbeitsbedingungen etwa im Sozial- und Pflege-dienst\u00a0investieren, sodass endlich wieder mehr Menschen im sozialen Sektor arbeiten k\u00f6nnen und wollen?<\/p>\n\n\n\n<p>Tats\u00e4chlich ist es einfach so: Dienstleistende sind vergleichsweise g\u00fcnstig. Der H\u00f6chstbetrag f\u00fcr das Taschengeld im FSJ und BFD liegt 2025 bei <a href=\"https:\/\/www.bundes-freiwilligendienst.de\/fsj-freiwilliges-soziales-jahr\/verguetung-leistungen-vorteile-gehalt-taschengeld.html\">644 Euro f\u00fcr eine Vollzeitstelle<\/a>. So viel Geld bekommen allerdings die Wenigsten. In Th\u00fcringen sind es im Kulturbereich momentan <a href=\"https:\/\/www.lkjthueringen.de\/projekte\/freiwilligendienste\/ich-will-freiwillige-r-werden\">350 Euro im Monat<\/a>. Es scheint also vermeintlich wirtschaftlicher zu sein, jeden Jahrgang junger Menschen f\u00fcr zw\u00f6lf Monate und kaum Geld in soziale Einrichtungen zu stecken, statt Mittel in die Hand zu nehmen und langfristige L\u00f6sungen zu schaffen. Das w\u00e4re zwar eine deutlich nachhaltigere Investition, aber im ersten Moment auch eine nochmal deutlich teurere \u2013 da wirkt die Alternative anscheinend attraktiver.<\/p>\n\n\n\n<p>Das Taschengeld in dieser Form ist dar\u00fcber hinaus ein Argument gegen eine Verpflichtung. Ein Jahr mit so wenig Geld zu leben, muss man sich leisten k\u00f6nnen. Bis zur Vollendung des 25. Lebensjahres besteht zwar Anspruch auf Kindergeld und auch Wohngeld kann beantragt werden, aber die Lebenshaltungskosten deckt das kaum. Ohne finanzielle Unterst\u00fctzung durch die Eltern ist ein Jugendfreiwilligendienst kaum stemmbar. Nun Menschen jeder \u00f6konomischen Schicht in ein solches Lebensverh\u00e4ltnis zu zwingen, w\u00e4re nichts weiter als klassistisch. Nat\u00fcrlich k\u00f6nnte man das Taschengeld erh\u00f6hen; was wiederum eine deutliche Mehrausgabe f\u00fcr einen Staat w\u00e4re, der ja jetzt schon kaum bereit ist, die bestehenden Taschengelder an die aktuellen Lebenserhaltungskosten anzupassen. Mein pers\u00f6nliches Fazit: <em>Wollen<\/em> junge Menschen sich freiwillig engagieren, ist das nicht wichtig genug, um es ausreichend zu finanzieren \u2013 doch eine Verpflichtung w\u00e4re seitens der Verantwortlichen\/der Politik so sehr zu bef\u00fcrworten, dass man bereit w\u00e4re, daf\u00fcr sehr gro\u00dfe Summen in die Hand zu nehmen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ausbauf\u00e4hig<\/h3>\n\n\n\n<p>Wer m\u00f6chte, dass sich mehr junge Leute gezielt ein Jahr lang gemeinn\u00fctzig engagieren, sollte sie nicht zwingen, sondern das Engagement attraktiver gestalten. Wenn ich sage, ich bin Fan des Jugendfreiwilligendienstes, dann hei\u00dft das nicht, dass ich komplett zufrieden mit dessen Konzeption bin; im Gegenteil. An konkreten Stellen ist Jugendfreiwilligendienst erheblich ausbauf\u00e4hig:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Oft wird Freiwilligendienst als eine Art Umweg im Lebenslauf angesehen, der kaum Mehrwert f\u00fcr den weiteren Arbeits- oder Karriereweg besitzt; ein &#8220;Ich wusste halt nicht, was ich nach dem Abi machen sollte&#8221;, was \u2013 nebenbei bemerkt \u2013 meines Erachtens eine vollkommen legitime Situation ist. Erworbene Kompetenzen und pers\u00f6nliches Wachstum werden sp\u00e4ter kaum gesehen oder erfragt.<\/li>\n\n\n\n<li>Des Weiteren stellt sich die Frage, wer \u00fcberhaupt Zugang zu einem Freiwilligendienst hat. Im Kulturbereich mit seinen Einsatzstellen in Theatern und Museen f\u00e4llt es besonders ins Auge: Hier sind kaum Freiwillige aus \u00e4rmeren Schichten vertreten. Auch zu Einsatzstellen wie Sportvereinen oder Naturschutzgebieten haben armutsbetroffene Kinder und Jugendliche zuvor oft keine direkte Verbindung. Es ist nicht nur das geringe Taschengeld, das ihnen diese Form der Teilhabe verwehrt.<\/li>\n\n\n\n<li>Die Freiheit der Tr\u00e4ger kann ebenso problematisch sein. Wie erw\u00e4hnt ist ihr Job die Begleitung der Freiwilligen durch ihr Jahr. Dazu kommt die Gestaltung von sogenannten Bildungstagen. Gesetzlich sind im zw\u00f6lfmonatigen Freiwilligendienst mindestens 25 Bildungstage vorgeschrieben. Ein Gro\u00dfteil davon wird in Form von Seminarfahrten absolviert, wo Freiwilligendienstleistende in Gruppen gemeinsam mit Mitarbeitenden ihres Tr\u00e4gers f\u00fcr eine knappe Woche gemeinsam verreisen. Neben dem Austausch mit anderen Freiwilligen nehmen sie hier an Bildungsangeboten teil, die eigenverantwortlich vom Tr\u00e4ger gestaltet werden und deren Schwerpunkte sich an der Ausrichtung des Dienstes orientieren. Das schafft Flexibilit\u00e4t in Struktur und Inhalt, aber die Qualit\u00e4t dieser Bildungsangebote wird nicht nennenswert gepr\u00fcft. Gleiches gilt f\u00fcr die Begleitung der Freiwilligen in ihrem Arbeitsalltag.<\/li>\n<\/ul>\n\n\n\n<p>Der Tr\u00e4ger spielt also eine wichtige Rolle bei der Qualit\u00e4t des Freiwilligendienstes, seine Mitarbeitenden sollen <em>die<\/em> Ansprechpersonen bei Problemen sein, die im Laufe des Jahres auftreten \u2013 aber was tun, wenn tats\u00e4chlich der Tr\u00e4ger das Problem ist? Diese Erfahrung m\u00fcssen Freiwillige jedes Jahr aufs Neue machen. Nicht alle f\u00fchlen sich bei ihrem Tr\u00e4ger und mit dessen Arbeit wohl. Also, welche M\u00f6glichkeiten hat der:die Freiwilligendienstleistende bei starker Unzufriedenheit? Er:sie kann sich an offizielle Vertreter:innen aus der Sozialpolitik wenden! Da ist noch viel Potenzial, das Ganze etwas niedrigschwelliger zu gestalten f\u00fcr die jungen Leute.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Hallo? H\u00f6rt uns jemand?<\/h3>\n\n\n\n<p>\u00dcberhaupt ist das mit der Interessenvertretung von Freiwilligendienstleistenden so eine Sache. Kinder und junge Menschen haben gemeinhin kaum politisches und gesellschaftliches Mitsprache- und Gestaltungsrecht. Der Freiwilligendienst selbst f\u00e4llt bei verantwortlichen Politiker:innen im Sozialbereich neben all den \u201egr\u00f6\u00dferen\u201c Themen wie Schule oft unter den Tisch.<\/p>\n\n\n\n<p>Einige Tr\u00e4ger wie etwa der <a href=\"https:\/\/www.bkj.de\/\">Dachverband Bundesvereinigung Kulturelle Kinder- und Jugendbildung e.V.<\/a> und seine Ableger in den einzelnen Bundesl\u00e4ndern haben sich selbst zur Einrichtung einer Freiwilligenvertretung verpflichtet. Es ist ein Ehrenamt, das Freiwillige zus\u00e4tzlich zu ihrer Arbeit in der Einsatzstelle annehmen k\u00f6nnen, um sich f\u00fcr die Belange von Jugendfreiwilligendienstleistenden einzusetzen. Ein Beispiel daf\u00fcr ist die Aktion <a href=\"https:\/\/bak-fsj.de\/themen\/freiefahrt\/\">#freiefahrtfuerfreiwillige<\/a>, mit der eine kostenlose Nutzung des \u00d6PNVs f\u00fcr Freiwillige gefordert wird. Die aktuell 63 Euro f\u00fcr das Deutschlandticket sind schlicht ein zu hoher Kostenpunkt im geringen Taschengeld, zumal viele Freiwillige auf \u00f6ffentliche Verkehrsmittel angewiesen sind, um zu ihrer Arbeit zu gelangen. Die Freiwilligenvertretung ist der Versuch nachhaltiger Lobbyarbeit, die auch immer mal Fr\u00fcchte tr\u00e4gt, aber wie gesagt: Geh\u00f6rt wird die Gruppe der Freiwilligen selten und die zus\u00e4tzliche Arbeit mit der Begleitung einer Freiwilligenvertretung machen sich auch nicht alle Tr\u00e4ger.<\/p>\n\n\n\n<p>Au\u00dferdem ist die immanente Fluktuation des Freiwilligendienstes ein Hindernis f\u00fcr ein kontinuierliches Wirken auf die Politik. Wenn in jedem Jahr neue Menschen kommen, f\u00fcr die auch noch der Einstieg in den Freiwilligendienst und die neue Lebensphase mitunter recht stressig und fordernd ist, wird eine konstante Arbeit zur nachhaltigen Verbesserung deutlich erschwert. Tr\u00e4ger engagieren sich ebenfalls dahingehend, aber dies reicht nicht aus. Die Stimmen von \u201eBetroffenen\u201c, also von Freiwilligen, sind ein unabdingbarer Aspekt der Arbeit. Und: \u201eEs ist nur f\u00fcr ein Jahr.\u201c \u2013 Ich vermute, dass das auch viele von einem st\u00e4rkeren Engagement abh\u00e4lt. Wer sich w\u00e4hrend seines:ihres Freiwilligendienstes f\u00fcr Ver\u00e4nderungen stark macht, arbeitet dabei in erster Linie f\u00fcr kommende Jahrg\u00e4nge, nicht f\u00fcr sich selbst.<\/p>\n\n\n\n<p>Also alles recht hoffnungslos? Nicht ganz! Im April 2023 riefen Sprecher:innen verschiedener Freiwilligenvertretungen die Kampagne <a href=\"https:\/\/fwd-staerken.de\/\">&#8220;Freiwilligendienste st\u00e4rken&#8221;<\/a> ins Leben. Mithilfe einer Petition wollten sie f\u00fcr Verbesserungen werben; genau im Petitionszeitraum wurde jener eingangs erw\u00e4hnte Bundeshaushaltsentwurf vorgelegt, der f\u00fcr 2024 die K\u00fcrzungen in H\u00f6he von 78 Millionen Euro vorsah. Ad hoc verlegten die Aktivist:innen den Schwerpunkt der Petition auf die finanzielle Sicherung des Freiwilligendienstes. Das Quorum lag bei 50.000 Unterschriften, am Ende konnten sie \u00fcber 100.000 sammeln. Es war jene Petition, die die K\u00fcrzungen im Bundeshaushalt zun\u00e4chst verhinderte.<\/p>\n\n\n\n<p class=\"has-content-bg-alt-background-color has-background\">Der zweite Teil zu diesem Beitrag wird April 2026 auf unserer Seite erscheinen, unter dem Titel \u201eMit Freiwilligen auf Augenh\u00f6he: \u00dcber den pers\u00f6nlichen Wert des Jugendfreiwilligendienstes\u201c. Wer ihn nicht verpassen m\u00f6chte: Gerne auf <a href=\"https:\/\/www.instagram.com\/voluntariness.freiwilligkeit\/\">Instagram<\/a> oder <a href=\"https:\/\/bsky.app\/profile\/freiwilligkeit.bsky.social\">Bluesky<\/a> folgen! Stay tuned!<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p class=\"has-content-bg-alt-background-color has-background\"><span class=\"has-inline-color has-content-primary-color\">Zitiervorschlag:<\/span> H\u00e4hnlein, Ronja: &#8220;Jugendfreiwilligendienst als Gewinn? Eine Kosten-Nutzen-Rechnung mit Erfahrungswerten&#8221;, <em>Freiwilligkeit: Geschichte | Gesellschaft | Theorie<\/em>, Februar 2026, <a href=\"https:\/\/www.voluntariness.org\/de\/jugendfreiwilligendienst-als-gewinn\/\">https:\/\/www.voluntariness.org\/de\/jugendfreiwilligendienst-als-gewinn\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Ronja H\u00e4hnlein<\/p>\n<p>Sie z\u00e4hlen Zugv\u00f6gel, sie teilen Mittagessen aus, sie schneiden Radiosendungen \u2013 Freiwilligendienst-leistende widmen ein Jahr ihres Lebens dem gesellschaftlichen Engagement. Doch welche Anerkennung findet das? Welchen Stellenwert hat der Dienst in Politik und Gesellschaft? Wie wichtig ist der Charakter der Freiwilligkeit? Ein Kommentar von Ronja H\u00e4hnlein, ehemalige FSJlerin und Teamerin von Freiwilligen im Th\u00fcringer Kultur- und Politikbereich.<\/p>\n","protected":false},"author":4,"featured_media":15991,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[152,3],"tags":[475,474,444,443],"class_list":["post-15969","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-de","category-unkategorisiert","tag-debatte","tag-freiwilligendienst","tag-krise-de-2","tag-pflicht-de"],"_links":{"self":[{"href":"https:\/\/www.voluntariness.org\/de\/wp-json\/wp\/v2\/posts\/15969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.voluntariness.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.voluntariness.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.voluntariness.org\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.voluntariness.org\/de\/wp-json\/wp\/v2\/comments?post=15969"}],"version-history":[{"count":78,"href":"https:\/\/www.voluntariness.org\/de\/wp-json\/wp\/v2\/posts\/15969\/revisions"}],"predecessor-version":[{"id":16414,"href":"https:\/\/www.voluntariness.org\/de\/wp-json\/wp\/v2\/posts\/15969\/revisions\/16414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.voluntariness.org\/de\/wp-json\/wp\/v2\/media\/15991"}],"wp:attachment":[{"href":"https:\/\/www.voluntariness.org\/de\/wp-json\/wp\/v2\/media?parent=15969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.voluntariness.org\/de\/wp-json\/wp\/v2\/categories?post=15969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.voluntariness.org\/de\/wp-json\/wp\/v2\/tags?post=15969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}